{"id":2396,"date":"2026-02-26T10:02:35","date_gmt":"2026-02-26T10:02:35","guid":{"rendered":"https:\/\/nirotec.de\/sobre-nosotros\/"},"modified":"2026-08-26T08:25:12","modified_gmt":"2026-08-26T08:25:12","slug":"sobre-nosotros","status":"publish","type":"page","link":"https:\/\/nirotec.de\/es\/sobre-nosotros\/","title":{"rendered":"Sobre nosotros"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section et_pb_section_parallax section_has_divider et_pb_bottom_divider preset--module--divi-section--74c69059-8e69-4122-b1e6-dfeabf6c5711\"><span class=\"et-pb-parallax-wrapper\"><span class=\"et-pb-parallax-background et-pb-parallax-background-module--divi-section-0\" style=\"background-image:linear-gradient(242deg, #004288 0%,rgba(0,0,0,0.9) 74% 100%), url(https:\/\/nirotec.de\/wp-content\/uploads\/2026\/04\/Jack-Kulcke-2.jpg);background-color:initial;background-blend-mode:multiply\"><\/span><\/span>\n<div class=\"et_pb_row_0 et_pb_row et_block_row preset--module--divi-row--5138c454-be54-4233-bd3b-f8e6a8747976\">\n<div class=\"et_pb_column_0 et_pb_column et_pb_column_2_3 et_block_column et_pb_css_mix_blend_mode_passthrough preset--module--divi-column--73121f80-a3ef-4484-8763-c3f18e3c56d2\">\n<div class=\"et_pb_heading_0 et_pb_heading et_pb_module et_block_module preset--module--divi-heading--ddeb8c09-9078-4424-bc15-2efb6572e28e\"><div class=\"et_pb_heading_container\"><h1 class=\"et_pb_module_header\">Fabricante y distribuidor de accesorios de tuber\u00eda sin soldadura desde 1988<\/h1><\/div><\/div>\n\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--0504de1e-f5ff-4281-ba60-cbbe4edf98bc\"><div class=\"et_pb_text_inner\"><p>Nirotec es fabricante y suministrador de accesorios de tuber\u00eda sin soldadura para sistemas de tuber\u00edas industriales. Con conformado propio en Unna y un aprovisionamiento selectivo a trav\u00e9s de una red internacional, suministramos componentes para proyectos con las m\u00e1ximas exigencias t\u00e9cnicas: desde componentes est\u00e1ndar seg\u00fan EN y ASME hasta soluciones especiales en materiales especiales para proyectos concretos.<\/p>\n<p>Como empresa de tama\u00f1o medio, combinamos la flexibilidad de un especialista con los est\u00e1ndares de calidad de la gran industria: certificados conforme a ISO 9001 y AD 2000.<\/p>\n<div>\n<div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_1 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough preset--module--divi-column--73121f80-a3ef-4484-8763-c3f18e3c56d2\"><\/div>\n<\/div>\n<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div><\/div>\n\n<div class=\"et_pb_section_1 et_pb_section et_section_regular et_block_section section_has_divider et_pb_bottom_divider preset--module--divi-section--default\">\n<div class=\"et_pb_row_1 et_pb_row et_block_row preset--module--divi-row--default\">\n<div class=\"et_pb_column_2 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough preset--module--divi-column--default\">\n<div class=\"et_pb_heading_1 et_pb_heading et_pb_module et_block_module preset--module--divi-heading--c33f07d9-41e0-421a-8799-5799df695cce\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Connecting Pipelines \u2013 desde 1988<\/h2><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_2 et_pb_row et_block_row preset--module--divi-row--default\">\n<div class=\"et_pb_column_3 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough preset--module--divi-column--default\">\n<div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--2c55a9c4-feed-423b-9edb-ae0b5b365cac\"><div class=\"et_pb_text_inner\"><p><span data-canva-clipboard=\"ewAiAGEAIgA6ADUALAAiAGgAIgA6ACIAdwB3AHcALgBjAGEAbgB2AGEALgBjAG8AbQAiACwAIgBjACIAOgAiAEQAQQBHADEAcwBfADIATAByAG4AWQAiACwAIgBpACIAOgAiAFoASABLAEcAcAA3AHIANAA5AHgATQA1AEEARAB1AEIAUwBQAHMAcgBOAEEAIgAsACIAYgAiADoAMQA3ADcAMQAxADYANQAxADgAOQAxADgAMQAsACIAQQA\/ACIAOgAiAEUAIgAsACIAQQAiADoAewAiAEEAIgA6AFsAewAiAEEAIgA6AHsAIgBBAD8AIgA6ACIAQQAiACwAIgBBACIAOgAiAFMAZQBpAHQAIABmAGEAcwB0ACAAegB3AGUAaQAgAEoAYQBoAHIAegBlAGgAbgB0AGUAbgAgAHMAdABlAGgAdAAgAE4AaQByAG8AdABlAGMAIABmAPwAcgAgAFAAcgDkAHoAaQBzAGkAbwBuACAAaQBuACAAZABlAHIAIABGAGUAcgB0AGkAZwB1AG4AZwAgAHYAbwBuACAAIgB9ACwAIgBCACIAOgB7ACIAQQAiADoAIgBZAEEARgBkAEoAagBUAGsANQBVAFUALAAwACIALAAiAEEAPwAiADoAIgBCAF8AIgB9AH0ALAB7ACIAQQAiADoAewAiAEEAPwAiADoAIgBBACIALAAiAEEAIgA6ACIAUgBvAGgAcgBmAG8AcgBtAHQAZQBpAGwAZQBuACIAfQAsACIAQgAiADoAewAiAEMAIgA6ACIAYgBvAGwAZAAiACwAIgBBAD8AIgA6ACIAQgBfACIAfQB9ACwAewAiAEEAIgA6AHsAIgBBAD8AIgA6ACIAQQAiACwAIgBBACIAOgAiACwAIAAiAH0ALAAiAEMAIgA6AHsAIgBDACIAOgB0AHIAdQBlACwAIgBBAD8AIgA6ACIAQgBfACIAfQB9ACwAewAiAEEAIgA6AHsAIgBBAD8AIgA6ACIAQQAiACwAIgBBACIAOgAiAEYAaQB0AHQAaQBuAGcAcwAiAH0ALAAiAEIAIgA6AHsAIgBDACIAOgAiAGIAbwBsAGQAIgAsACIAQQA\/ACIAOgAiAEIAXwAiAH0AfQAsAHsAIgBBACIAOgB7ACIAQQA\/ACIAOgAiAEEAIgAsACIAQQAiADoAIgAgAHUAbgBkACAAIgB9ACwAIgBDACIAOgB7ACIAQwAiADoAdAByAHUAZQAsACIAQQA\/ACIAOgAiAEIAXwAiAH0AfQAsAHsAIgBBACIAOgB7ACIAQQA\/ACIAOgAiAEEAIgAsACIAQQAiADoAIgBTAG8AbgBkAGUAcgBsAPYAcwB1AG4AZwBlAG4AIgB9ACwAIgBCACIAOgB7ACIAQwAiADoAIgBiAG8AbABkACIALAAiAEEAPwAiADoAIgBCAF8AIgB9AH0ALAB7ACIAQQAiADoAewAiAEEAPwAiADoAIgBBACIALAAiAEEAIgA6ACIAIABhAHUAcwAgAEUAZABlAGwAcwB0AGEAaABsACAAdQBuAGQAIABTAG8AbgBkAGUAcgB3AGUAcgBrAHMAdABvAGYAZgBlAG4ALgBcAG4AVQBuAHMAZQByAGUAIABLAG8AbQBwAG8AbgBlAG4AdABlAG4AIABrAG8AbQBtAGUAbgAgAGQAbwByAHQAIAB6AHUAbQAgAEUAaQBuAHMAYQB0AHoALAAgAHcAbwAgAHQAZQBjAGgAbgBpAHMAYwBoAGUAIABaAHUAdgBlAHIAbADkAHMAcwBpAGcAawBlAGkAdAAgAGUAbgB0AHMAYwBoAGUAaQBkAGUAbgBkACAAaQBzAHQAIAATICAAaQBuACAAZABlAHIAIAAiAH0ALAAiAEMAIgA6AHsAIgBDACIAOgB0AHIAdQBlACwAIgBBAD8AIgA6ACIAQgBfACIAfQB9ACwAewAiAEEAIgA6AHsAIgBBAD8AIgA6ACIAQQAiACwAIgBBACIAOgAiAEUAbgBlAHIAZwBpAGUAZQByAHoAZQB1AGcAdQBuAGcAIgB9ACwAIgBCACIAOgB7ACIAQwAiADoAIgBiAG8AbABkACIALAAiAEEAPwAiADoAIgBCAF8AIgB9AH0ALAB7ACIAQQAiADoAewAiAEEAPwAiADoAIgBBACIALAAiAEEAIgA6ACIALAAgACIAfQAsACIAQwAiADoAewAiAEMAIgA6AHQAcgB1AGUALAAiAEEAPwAiADoAIgBCAF8AIgB9AH0ALAB7ACIAQQAiADoAewAiAEEAPwAiADoAIgBBACIALAAiAEEAIgA6ACIAQwBoAGUAbQBpAGUAaQBuAGQAdQBzAHQAcgBpAGUAIgB9ACwAIgBCACIAOgB7ACIAQwAiADoAIgBiAG8AbABkACIALAAiAEEAPwAiADoAIgBCAF8AIgB9AH0ALAB7ACIAQQAiADoAewAiAEEAPwAiADoAIgBBACIALAAiAEEAIgA6ACIALAAgACIAfQAsACIAQwAiADoAewAiAEMAIgA6AHQAcgB1AGUALAAiAEEAPwAiADoAIgBCAF8AIgB9AH0ALAB7ACIAQQAiADoAewAiAEEAPwAiADoAIgBBACIALAAiAEEAIgA6ACIATgB1AGsAbABlAGEAcgB0AGUAYwBoAG4AaQBrACIAfQAsACIAQgAiADoAewAiAEMAIgA6ACIAYgBvAGwAZAAiACwAIgBBAD8AIgA6ACIAQgBfACIAfQB9ACwAewAiAEEAIgA6AHsAIgBBAD8AIgA6ACIAQQAiACwAIgBBACIAOgAiACAAcwBvAHcAaQBlACAAaQBtACAAIgB9ACwAIgBDACIAOgB7ACIAQwAiADoAdAByAHUAZQAsACIAQQA\/ACIAOgAiAEIAXwAiAH0AfQAsAHsAIgBBACIAOgB7ACIAQQA\/ACIAOgAiAEEAIgAsACIAQQAiADoAIgBBAHAAcABhAHIAYQB0AGUAIgB9ACwAIgBCACIAOgB7ACIAQwAiADoAIgBiAG8AbABkACIALAAiAEEAPwAiADoAIgBCAF8AIgB9AH0ALAB7ACIAQQAiADoAewAiAEEAPwAiADoAIgBBACIALAAiAEEAIgA6ACIALQAgAHUAbgBkACIAfQAsACIAQwAiADoAewAiAEMAIgA6AHQAcgB1AGUALAAiAEEAPwAiADoAIgBCAF8AIgB9AH0ALAB7ACIAQQAiADoAewAiAEEAPwAiADoAIgBBACIALAAiAEEAIgA6ACIAIABBAG4AbABhAGcAZQBuAGIAYQB1AC4AXABuACIAfQAsACIAQgAiADoAewAiAEMAIgA6ACIAYgBvAGwAZAAiACwAIgBBAD8AIgA6ACIAQgBfACIAfQB9ACwAewAiAEEAIgA6AHsAIgBBAD8AIgA6ACIAQQAiACwAIgBBACIAOgAiAFwAbgBBAGwAcwAgAHMAcABlAHoAaQBhAGwAaQBzAGkAZQByAHQAZQByACAASABlAHIAcwB0AGUAbABsAGUAcgAgAG0AaQB0ACAAZQBpAGcAZQBuAGUAcgAgAEYAZQByAHQAaQBnAHUAbgBnACAAZQBuAHQAdwBpAGMAawBlAGwAbgAgAHUAbgBkACAAcAByAG8AZAB1AHoAaQBlAHIAZQBuACAAdwBpAHIAIABCAGEAdQB0AGUAaQBsAGUALAAgAGQAaQBlACAAaAD2AGMAaABzAHQAZQBuACAAQQBuAHMAcAByAPwAYwBoAGUAbgAgAGEAbgAgAE0AYQDfAGgAYQBsAHQAaQBnAGsAZQBpAHQALAAgAE0AYQB0AGUAcgBpAGEAbABxAHUAYQBsAGkAdADkAHQAIAB1AG4AZAAgAEQAbwBrAHUAbQBlAG4AdABhAHQAaQBvAG4AIABnAGUAcgBlAGMAaAB0ACAAdwBlAHIAZABlAG4ALgAiAH0ALAAiAEMAIgA6AHsAIgBDACIAOgB0AHIAdQBlACwAIgBBAD8AIgA6ACIAQgBfACIAfQB9AF0AfQB9AA==\"><\/span><\/p>\n<div>\n<p><span>Desde hace m\u00e1s de 35 a\u00f1os, Nirotec suministra accesorios de tuber\u00eda para proyectos industriales exigentes en el sector energ\u00e9tico, la tecnolog\u00eda nuclear, la petroqu\u00edmica, el offshore y la industria de proceso. Lo que empez\u00f3 como un especialista en accesorios sin soldadura es hoy un socio consolidado para constructores de instalaciones, contratistas EPC y operadores en Europa y en todo el mundo. <\/span><\/p>\n<p><strong>Nuestra fortaleza reside en la combinaci\u00f3n de:<\/strong><br \/><strong><\/strong><\/p>\n<ul>\n<li><span>Fabricaci\u00f3n propia para dimensiones especiales y materiales especiales<\/span><br \/><span><\/span><span><\/span><\/li>\n<li><span>Aprovisionamiento espec\u00edfico para componentes est\u00e1ndar y suministros completos<\/span><br \/><span><\/span><span><\/span><\/li>\n<li><span>Documentaci\u00f3n completa de aseguramiento de la calidad (QS) tambi\u00e9n para sectores cr\u00edticos para la seguridad<\/span><br \/><span><\/span><span><\/span><\/li>\n<li><span>Alta capacidad de respuesta como empresa mediana<\/span><\/li>\n<\/ul>\n<div><\/div>\n<div><\/div>\n<\/div>\n<div><\/div>\n<\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_4 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough preset--module--divi-column--default\">\n<div class=\"et_pb_image_0 et_pb_image et_pb_module et_block_module preset--module--divi-image--1cc6152f-565c-4c4d-b0c9-cf8c9576c341\"><span class=\"et_pb_image_wrap\"><img alt=\"\" alt=\"\" decoding=\"async\" src=\"https:\/\/nirotec.de\/wp-content\/uploads\/2026\/02\/Nirotec-Mitarbeiter-.jpg\" width=\"800\" height=\"600\" srcset=\"https:\/\/nirotec.de\/wp-content\/uploads\/2026\/02\/Nirotec-Mitarbeiter-.jpg 800w, https:\/\/nirotec.de\/wp-content\/uploads\/2026\/02\/Nirotec-Mitarbeiter--480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" class=\"wp-image-142\" title=\"Empleados de Nirotec\" \/><\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div><\/div>\n\n<div class=\"et_pb_section_2 et_pb_section et_section_regular et_block_section section_has_divider et_pb_top_divider preset--module--divi-section--default\"><div class=\"et_pb_top_inside_divider et-no-transition\"><\/div>\n<div class=\"et_pb_row_3 et_pb_row et_block_row preset--module--divi-row--5138c454-be54-4233-bd3b-f8e6a8747976\">\n<div class=\"et_pb_column_5 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough preset--module--divi-column--73121f80-a3ef-4484-8763-c3f18e3c56d2\">\n<div class=\"et_pb_heading_2 et_pb_heading et_pb_module et_block_module preset--module--divi-heading--c33f07d9-41e0-421a-8799-5799df695cce\"><div class=\"et_pb_heading_container\"><h2 class=\"et_pb_module_header\">Nuestras capacidades de fabricaci\u00f3n<\/h2><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_4 et_pb_row et_block_row preset--module--divi-row--5138c454-be54-4233-bd3b-f8e6a8747976\">\n<div class=\"et_pb_column_6 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough preset--module--divi-column--73121f80-a3ef-4484-8763-c3f18e3c56d2\">\n<div class=\"et_pb_image_1 et_pb_image et_pb_module et_block_module preset--module--divi-image--1cc6152f-565c-4c4d-b0c9-cf8c9576c341\"><span class=\"et_pb_image_wrap\"><img alt=\"\" alt=\"\" decoding=\"async\" src=\"https:\/\/nirotec.de\/wp-content\/uploads\/2026\/02\/630_0900_3407049_Firma_Nirotec_Produktion_005.jpg\" width=\"640\" height=\"428\" srcset=\"https:\/\/nirotec.de\/wp-content\/uploads\/2026\/02\/630_0900_3407049_Firma_Nirotec_Produktion_005.jpg 640w\" sizes=\"(max-width: 640px) 100vw, 640px\" class=\"wp-image-70\" title=\"630_0900_3407049_Firma_Nirotec_Produktion_005\" \/><\/span><\/div>\n<\/div>\n\n<div class=\"et_pb_column_7 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough preset--module--divi-column--73121f80-a3ef-4484-8763-c3f18e3c56d2\">\n<div class=\"et_pb_heading_3 et_pb_heading et_pb_module et_block_module preset--module--divi-heading--ba4a6336-701f-47b8-bf5c-09da0ce28016\"><div class=\"et_pb_heading_container\"><h3 class=\"et_pb_module_header\">Competencia tecnol\u00f3gica<\/h3><\/div><\/div>\n\n<div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--2c55a9c4-feed-423b-9edb-ae0b5b365cac\"><div class=\"et_pb_text_inner\"><p><span>Nuestras instalaciones de producci\u00f3n en Unna est\u00e1n especializadas en la fabricaci\u00f3n de accesorios de tuber\u00eda sin soldadura mediante conformado en fr\u00edo y en caliente, as\u00ed como mediante hidroconformado a alta presi\u00f3n interna (IHU).<\/span><\/p>\n<p><strong><span style=\"font-size: 16px;\">Datos t\u00e9cnicos:<\/span><\/strong><\/p>\n<ul>\n<li><span>Prensas hidr\u00e1ulicas de 150 a 1.500 toneladas<\/span><br \/><span><\/span><\/li>\n<li><span>Espesores de pared de hasta 100 mm<\/span><br \/><span><\/span><\/li>\n<li><span>Di\u00e1metros de hasta 610 mm<\/span><br \/><span><\/span><\/li>\n<li><span>Instalaciones de tratamiento t\u00e9rmico con hasta 10 m\u00b3 de volumen \u00fatil<\/span><br \/><span><\/span><\/li>\n<li><span>Sistema ITNS propio para requisitos de tecnolog\u00eda nuclear<\/span><br \/><span><\/span><\/li>\n<li><span>Mecanizado y acabado superficial<\/span><br \/><span><\/span><\/li>\n<li><span>Fabricaci\u00f3n propia de utillajes y moldes especiales<\/span><\/li>\n<\/ul>\n<p><span>Fabricamos codos, tes, reducciones y accesorios especiales seg\u00fan EN 10253 y ASME B16.9, en aceros no aleados, aceros inoxidables austen\u00edticos, d\u00faplex, s\u00faper d\u00faplex y aleaciones de n\u00edquel. Las fabricaciones especiales seg\u00fan plano son nuestro trabajo diario. <\/span><\/p>\n<p><span>Adem\u00e1s, nuestra instalaci\u00f3n permite fabricar codos y tes seg\u00fan EN 10253-2 tipo B, incluida la verificaci\u00f3n por c\u00e1lculo y por medici\u00f3n de la cota tint, as\u00ed como de las cotas Ts y Tb.<\/span><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-button--default\" href=\"https:\/\/nirotec.de\/es\/productos\/\">Nuestros productos de un vistazo<\/a><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_5 et_pb_row et_block_row preset--module--divi-row--5138c454-be54-4233-bd3b-f8e6a8747976\">\n<div class=\"et_pb_column_8 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough preset--module--divi-column--73121f80-a3ef-4484-8763-c3f18e3c56d2\">\n<div class=\"et_pb_heading_4 et_pb_heading et_pb_module et_block_module preset--module--divi-heading--ba4a6336-701f-47b8-bf5c-09da0ce28016\"><div class=\"et_pb_heading_container\"><h3 class=\"et_pb_module_header\">Calidad y requisitos normativos<\/h3><\/div><\/div>\n\n<div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--2c55a9c4-feed-423b-9edb-ae0b5b365cac\"><div class=\"et_pb_text_inner\"><p>Nuestros procesos de calidad est\u00e1n certificados seg\u00fan DIN EN ISO 9001. Adem\u00e1s, cumplimos los requisitos del reglamento AD 2000 (W0\/HP0) y de la Directiva Europea de Equipos a Presi\u00f3n. <\/p>\n<p>La certificaci\u00f3n seg\u00fan ISO 19443 (\u00e1mbito nuclear) se encuentra en preparaci\u00f3n. Disponemos de registros CRN para el mercado canadiense. <\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_1_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_1 et_pb_button et_pb_bg_layout_light et_pb_module et_flex_module preset--module--divi-button--default\" href=\"https:\/\/nirotec.de\/es\/certificados-y-homologaciones\/\">M\u00e1s sobre nuestras homologaciones y certificados<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_9 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough preset--module--divi-column--73121f80-a3ef-4484-8763-c3f18e3c56d2\">\n<div class=\"et_pb_image_2 et_pb_image et_pb_module et_block_module preset--module--divi-image--1cc6152f-565c-4c4d-b0c9-cf8c9576c341\"><span class=\"et_pb_image_wrap\"><img alt=\"\" alt=\"\" decoding=\"async\" src=\"https:\/\/nirotec.de\/wp-content\/uploads\/2026\/04\/JK_1008_v2_FulRes.jpg\" width=\"2362\" height=\"1576\" srcset=\"https:\/\/nirotec.de\/wp-content\/uploads\/2026\/04\/JK_1008_v2_FulRes.jpg 2362w, https:\/\/nirotec.de\/wp-content\/uploads\/2026\/04\/JK_1008_v2_FulRes-1280x854.jpg 1280w, https:\/\/nirotec.de\/wp-content\/uploads\/2026\/04\/JK_1008_v2_FulRes-980x654.jpg 980w, https:\/\/nirotec.de\/wp-content\/uploads\/2026\/04\/JK_1008_v2_FulRes-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2362px, 100vw\" class=\"wp-image-912\" title=\"\u00a9 Jack Kulcke\" \/><\/span><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_6 et_pb_row et_block_row preset--module--divi-row--5138c454-be54-4233-bd3b-f8e6a8747976\">\n<div class=\"et_pb_column_10 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough preset--module--divi-column--73121f80-a3ef-4484-8763-c3f18e3c56d2\">\n<div class=\"et_pb_image_3 et_pb_image et_pb_module et_block_module preset--module--divi-image--1cc6152f-565c-4c4d-b0c9-cf8c9576c341\"><span class=\"et_pb_image_wrap\"><img alt=\"\" alt=\"\" decoding=\"async\" src=\"https:\/\/nirotec.de\/wp-content\/uploads\/2026\/04\/Rohrbogen-Collage.jpg\" width=\"1920\" height=\"1080\" srcset=\"https:\/\/nirotec.de\/wp-content\/uploads\/2026\/04\/Rohrbogen-Collage.jpg 1920w, https:\/\/nirotec.de\/wp-content\/uploads\/2026\/04\/Rohrbogen-Collage-1280x720.jpg 1280w, https:\/\/nirotec.de\/wp-content\/uploads\/2026\/04\/Rohrbogen-Collage-980x551.jpg 980w, https:\/\/nirotec.de\/wp-content\/uploads\/2026\/04\/Rohrbogen-Collage-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1920px, 100vw\" class=\"wp-image-914\" title=\"Collage de codos\" \/><\/span><\/div>\n<\/div>\n\n<div class=\"et_pb_column_11 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough preset--module--divi-column--73121f80-a3ef-4484-8763-c3f18e3c56d2\">\n<div class=\"et_pb_heading_5 et_pb_heading et_pb_module et_block_module preset--module--divi-heading--ba4a6336-701f-47b8-bf5c-09da0ce28016\"><div class=\"et_pb_heading_container\"><h3 class=\"et_pb_module_header\">Gesti\u00f3n de proyectos y documentaci\u00f3n<\/h3><\/div><\/div>\n\n<div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-text--2c55a9c4-feed-423b-9edb-ae0b5b365cac\"><div class=\"et_pb_text_inner\"><p><span>Cada proyecto se gestiona conforme a un Inspection and Test Plan (ITP) individual. Toda la documentaci\u00f3n de ensayos y calidad se registra \u00edntegramente y se entrega junto con el suministro. <\/span><\/p>\n<p><span><br \/><\/span><strong>Servicios t\u00edpicos:<\/strong><\/p>\n<ul>\n<li><span>Elaboraci\u00f3n e implementaci\u00f3n de ITP espec\u00edficos de proyecto con puntos Hold y Witness<\/span><br \/><span><\/span><\/li>\n<li><span>Trazabilidad completa de materiales<\/span><br \/><span><\/span><\/li>\n<li><span>Certificados de inspecci\u00f3n seg\u00fan EN 10204 (3.1 \/ 3.2)<\/span><br \/><span><\/span><\/li>\n<li><span>Ensayos no destructivos (UT, RT, PT, MT)<\/span><br \/><span><\/span><\/li>\n<li><span>Identificaci\u00f3n positiva de materiales (PMI)<\/span><\/li>\n<li><span>Coordinaci\u00f3n de organismos de inspecci\u00f3n externos (T\u00dcV, SGS, Bureau Veritas, DNV)<\/span><br \/><span><\/span><\/li>\n<li><span>Inspecciones externas de clientes<\/span><\/li>\n<\/ul>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_3 et_pb_section et_section_regular et_block_section preset--module--divi-section--default\">\n<div class=\"et_pb_row_7 et_pb_row et_block_row preset--module--divi-row--5138c454-be54-4233-bd3b-f8e6a8747976\">\n<div class=\"et_pb_column_12 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough preset--module--divi-column--73121f80-a3ef-4484-8763-c3f18e3c56d2\">\n<div class=\"et_pb_cta_0 et_pb_promo et_pb_bg_layout_light et_animated et_pb_module et_block_module preset--module--divi-cta--be0cc754-576a-4b1c-868d-f6226f85de4d\"><div class=\"et_pb_promo_description\"><h2 class=\"et_pb_module_header\">\u00bfEst\u00e1 planificando un proyecto o necesita ayuda en la selecci\u00f3n de accesorios de tuber\u00eda?<\/h2><div class=\"et_pb_promo_content\"><p><span>P\u00f3ngase en contacto directamente con nuestro departamento t\u00e9cnico-comercial: aclararemos conjuntamente la disponibilidad, los materiales y el alcance del suministro.<\/span><\/p>\n<\/div><\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_2_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_2 et_pb_button et_pb_bg_layout_dark et_animated et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/nirotec.de\/es\/contacto\/\">Enviar consulta sin compromiso<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_4 et_pb_section et_section_regular et_block_section preset--module--divi-section--default\">\n<div class=\"et_pb_row_8 et_pb_row et_pb_equal_columns et_block_row preset--module--divi-row--default\">\n<div class=\"et_pb_column_13 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough et_animated preset--module--divi-column--50607da8-57bc-4d4b-aaef-f02e41c2cc4a\">\n<div class=\"et_pb_icon_0 et_pb_icon et_animated et_pb_module et_block_module\"><span class=\"et_pb_icon_wrap\"><span class=\"et-pb-icon\">\uf879<\/span><\/span><\/div>\n\n<div class=\"et_pb_blurb_0 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_top et_pb_module et_block_module ai_ignore_all preset--module--divi-blurb--212b201d-2c34-41bd-936c-851b7357d08b\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><div class=\"et_pb_blurb_description\"><p><span>+49 (0) 2303\/985 - 0<\/span><\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_14 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough et_animated preset--module--divi-column--50607da8-57bc-4d4b-aaef-f02e41c2cc4a\">\n<div class=\"et_pb_icon_1 et_pb_icon et_animated et_pb_module et_block_module\"><span class=\"et_pb_icon_wrap\"><span class=\"et-pb-icon\">\uf0e0<\/span><\/span><\/div>\n\n<div class=\"et_pb_blurb_1 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_top et_pb_module et_block_module ai_ignore_all preset--module--divi-blurb--212b201d-2c34-41bd-936c-851b7357d08b\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><div class=\"et_pb_blurb_description\"><p><a href=\"mailto:info@nirotec.de\" class=\"animsition-link\">info@nirotec.de<\/a><\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_15 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough et_animated preset--module--divi-column--50607da8-57bc-4d4b-aaef-f02e41c2cc4a\">\n<div class=\"et_pb_icon_2 et_pb_icon et_animated et_pb_module et_block_module\"><span class=\"et_pb_icon_wrap\"><span class=\"et-pb-icon\">\ue081<\/span><\/span><\/div>\n\n<div class=\"et_pb_blurb_2 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_top et_pb_module et_block_module ai_ignore_all preset--module--divi-blurb--212b201d-2c34-41bd-936c-851b7357d08b\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><div class=\"et_pb_blurb_description\"><p><span>Otto-Hahn-Str. 4<\/span><br \/><span>59423 Unna<\/span><\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_titles_title":"Nirotec \u2013 Fabricante y proveedor de accesorios de tuber\u00eda y soluciones especiales","_seopress_titles_desc":"Nirotec est\u00e1 especializada en Accesorios de tuber\u00eda de alta calidad, piezas especiales y peque\u00f1os lotes para aplicaciones industriales exigentes.","_seopress_robots_index":"yes","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-2396","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nirotec.de\/es\/wp-json\/wp\/v2\/pages\/2396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nirotec.de\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nirotec.de\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nirotec.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nirotec.de\/es\/wp-json\/wp\/v2\/comments?post=2396"}],"version-history":[{"count":12,"href":"https:\/\/nirotec.de\/es\/wp-json\/wp\/v2\/pages\/2396\/revisions"}],"predecessor-version":[{"id":2533,"href":"https:\/\/nirotec.de\/es\/wp-json\/wp\/v2\/pages\/2396\/revisions\/2533"}],"wp:attachment":[{"href":"https:\/\/nirotec.de\/es\/wp-json\/wp\/v2\/media?parent=2396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}